{"id":1274,"date":"2023-04-21T11:43:32","date_gmt":"2023-04-21T09:43:32","guid":{"rendered":"https:\/\/nuumagenetics.com\/?post_type=servicio&#038;p=73"},"modified":"2025-01-30T12:18:25","modified_gmt":"2025-01-30T11:18:25","slug":"secure-natal-basis","status":"publish","type":"servicio","link":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/","title":{"rendered":"Secure natal Basis"},"content":{"rendered":"<p>Der genetische pr\u00e4natale Test aus m\u00fctterlichem Blut ist ein nicht-invasiver Test, der ab der 10. Schwangerschaftswoche durchgef\u00fchrt werden kann.<\/p>\n<ul>\n<li>Erkennt genetische Ver\u00e4nderungen beim F\u00f6tus aus einer Blutprobe der Mutter.<\/li>\n<li>Sicher f\u00fcr Mutter und Kind.<\/li>\n<li>Geeignet f\u00fcr Mehrlingsschwangerschaften und Schwangerschaften durch assistierte Reproduktion mit Gametenspende.<\/li>\n<\/ul>\n","protected":false},"featured_media":373,"parent":0,"menu_order":35,"template":"","tipo_servicio":[19,21],"class_list":["post-1274","servicio","type-servicio","status-publish","has-post-thumbnail","hentry","tipo_servicio-praenatale-genetik","tipo_servicio-cribado-fetal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Secure natal Basis - Nuuma genetics<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secure natal Basis - Nuuma genetics\" \/>\n<meta property=\"og:description\" content=\"Der genetische pr\u00e4natale Test aus m\u00fctterlichem Blut ist ein nicht-invasiver Test, der ab der 10. Schwangerschaftswoche durchgef\u00fchrt werden kann. Erkennt genetische Ver\u00e4nderungen beim F\u00f6tus aus einer Blutprobe der Mutter. Sicher f\u00fcr Mutter und Kind. Geeignet f\u00fcr Mehrlingsschwangerschaften und Schwangerschaften durch assistierte Reproduktion mit Gametenspende.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuuma genetics\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-30T11:18:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/nuumagenetics.com\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/nuuma_text_02.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"390\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/prueba-genetica\\\/secure-natal-basis\\\/\",\"url\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/prueba-genetica\\\/secure-natal-basis\\\/\",\"name\":\"Secure natal Basis - Nuuma genetics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/prueba-genetica\\\/secure-natal-basis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/prueba-genetica\\\/secure-natal-basis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/nuuma_text_02.webp\",\"datePublished\":\"2023-04-21T09:43:32+00:00\",\"dateModified\":\"2025-01-30T11:18:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/prueba-genetica\\\/secure-natal-basis\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/prueba-genetica\\\/secure-natal-basis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/prueba-genetica\\\/secure-natal-basis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/nuuma_text_02.webp\",\"contentUrl\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/04\\\/nuuma_text_02.webp\",\"width\":390,\"height\":390},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/prueba-genetica\\\/secure-natal-basis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios\",\"item\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/pruebas-geneticas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Secure natal Basis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/\",\"name\":\"Nuuma genetics\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuumagenetics.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secure natal Basis - Nuuma genetics","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Secure natal Basis - Nuuma genetics","og_description":"Der genetische pr\u00e4natale Test aus m\u00fctterlichem Blut ist ein nicht-invasiver Test, der ab der 10. Schwangerschaftswoche durchgef\u00fchrt werden kann. Erkennt genetische Ver\u00e4nderungen beim F\u00f6tus aus einer Blutprobe der Mutter. Sicher f\u00fcr Mutter und Kind. Geeignet f\u00fcr Mehrlingsschwangerschaften und Schwangerschaften durch assistierte Reproduktion mit Gametenspende.","og_url":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/","og_site_name":"Nuuma genetics","article_modified_time":"2025-01-30T11:18:25+00:00","og_image":[{"width":390,"height":390,"url":"http:\/\/nuumagenetics.com\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/nuuma_text_02.avif","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/","url":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/","name":"Secure natal Basis - Nuuma genetics","isPartOf":{"@id":"https:\/\/nuumagenetics.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/#primaryimage"},"image":{"@id":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/#primaryimage"},"thumbnailUrl":"https:\/\/nuumagenetics.com\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/nuuma_text_02.webp","datePublished":"2023-04-21T09:43:32+00:00","dateModified":"2025-01-30T11:18:25+00:00","breadcrumb":{"@id":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/#primaryimage","url":"https:\/\/nuumagenetics.com\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/nuuma_text_02.webp","contentUrl":"https:\/\/nuumagenetics.com\/de\/wp-content\/uploads\/sites\/3\/2023\/04\/nuuma_text_02.webp","width":390,"height":390},{"@type":"BreadcrumbList","@id":"https:\/\/nuumagenetics.com\/de\/prueba-genetica\/secure-natal-basis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nuumagenetics.com\/de\/"},{"@type":"ListItem","position":2,"name":"Servicios","item":"https:\/\/nuumagenetics.com\/de\/pruebas-geneticas\/"},{"@type":"ListItem","position":3,"name":"Secure natal Basis"}]},{"@type":"WebSite","@id":"https:\/\/nuumagenetics.com\/de\/#website","url":"https:\/\/nuumagenetics.com\/de\/","name":"Nuuma genetics","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuumagenetics.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/nuumagenetics.com\/de\/wp-json\/wp\/v2\/servicio\/1274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuumagenetics.com\/de\/wp-json\/wp\/v2\/servicio"}],"about":[{"href":"https:\/\/nuumagenetics.com\/de\/wp-json\/wp\/v2\/types\/servicio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuumagenetics.com\/de\/wp-json\/wp\/v2\/media\/373"}],"wp:attachment":[{"href":"https:\/\/nuumagenetics.com\/de\/wp-json\/wp\/v2\/media?parent=1274"}],"wp:term":[{"taxonomy":"tipo_servicio","embeddable":true,"href":"https:\/\/nuumagenetics.com\/de\/wp-json\/wp\/v2\/tipo_servicio?post=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}